{"id":4009,"count":1,"description":"","link":"https:\/\/newyork1.one\/en\/tag\/waldorf","name":"Waldorf","slug":"waldorf","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/newyork1.one\/en\/wp-json\/wp\/v2\/tags\/4009","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newyork1.one\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/newyork1.one\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/newyork1.one\/en\/wp-json\/wp\/v2\/posts?tags=4009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}